{"id":950,"count":1,"description":"","link":"https:\/\/www.fenixamortecedores.com.br\/blog\/tag\/empresa-de-kit-de-rosca\/","name":"Empresa de kit de rosca","slug":"empresa-de-kit-de-rosca","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arquivo de Empresa de kit de rosca - Fenix Amortecedores<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fenixamortecedores.com.br\/blog\/tag\/empresa-de-kit-de-rosca\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Empresa de kit de rosca - Fenix Amortecedores\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fenixamortecedores.com.br\/blog\/tag\/empresa-de-kit-de-rosca\/\" \/>\n<meta property=\"og:site_name\" content=\"Fenix Amortecedores\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.fenixamortecedores.com.br\/blog\/tag\/empresa-de-kit-de-rosca\/\",\"url\":\"https:\/\/www.fenixamortecedores.com.br\/blog\/tag\/empresa-de-kit-de-rosca\/\",\"name\":\"Arquivo de Empresa de kit de rosca - Fenix Amortecedores\",\"isPartOf\":{\"@id\":\"https:\/\/www.fenixamortecedores.com.br\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.fenixamortecedores.com.br\/blog\/tag\/empresa-de-kit-de-rosca\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fenixamortecedores.com.br\/blog\/tag\/empresa-de-kit-de-rosca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.fenixamortecedores.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empresa de kit de rosca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fenixamortecedores.com.br\/blog\/#website\",\"url\":\"https:\/\/www.fenixamortecedores.com.br\/blog\/\",\"name\":\"Fenix Amortecedores\",\"description\":\"Especialistas em Remanufatura de Amortecedores\",\"publisher\":{\"@id\":\"https:\/\/www.fenixamortecedores.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fenixamortecedores.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fenixamortecedores.com.br\/blog\/#organization\",\"name\":\"Fenix Amortecedores\",\"url\":\"https:\/\/www.fenixamortecedores.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.fenixamortecedores.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fenixamortecedores.com.br\/blog\/wp-content\/uploads\/2024\/10\/logo-7.webp\",\"contentUrl\":\"https:\/\/www.fenixamortecedores.com.br\/blog\/wp-content\/uploads\/2024\/10\/logo-7.webp\",\"width\":253,\"height\":55,\"caption\":\"Fenix Amortecedores\"},\"image\":{\"@id\":\"https:\/\/www.fenixamortecedores.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de Empresa de kit de rosca - Fenix Amortecedores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fenixamortecedores.com.br\/blog\/tag\/empresa-de-kit-de-rosca\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de Empresa de kit de rosca - Fenix Amortecedores","og_url":"https:\/\/www.fenixamortecedores.com.br\/blog\/tag\/empresa-de-kit-de-rosca\/","og_site_name":"Fenix Amortecedores","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.fenixamortecedores.com.br\/blog\/tag\/empresa-de-kit-de-rosca\/","url":"https:\/\/www.fenixamortecedores.com.br\/blog\/tag\/empresa-de-kit-de-rosca\/","name":"Arquivo de Empresa de kit de rosca - Fenix Amortecedores","isPartOf":{"@id":"https:\/\/www.fenixamortecedores.com.br\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.fenixamortecedores.com.br\/blog\/tag\/empresa-de-kit-de-rosca\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fenixamortecedores.com.br\/blog\/tag\/empresa-de-kit-de-rosca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.fenixamortecedores.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Empresa de kit de rosca"}]},{"@type":"WebSite","@id":"https:\/\/www.fenixamortecedores.com.br\/blog\/#website","url":"https:\/\/www.fenixamortecedores.com.br\/blog\/","name":"Fenix Amortecedores","description":"Especialistas em Remanufatura de Amortecedores","publisher":{"@id":"https:\/\/www.fenixamortecedores.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fenixamortecedores.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.fenixamortecedores.com.br\/blog\/#organization","name":"Fenix Amortecedores","url":"https:\/\/www.fenixamortecedores.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.fenixamortecedores.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.fenixamortecedores.com.br\/blog\/wp-content\/uploads\/2024\/10\/logo-7.webp","contentUrl":"https:\/\/www.fenixamortecedores.com.br\/blog\/wp-content\/uploads\/2024\/10\/logo-7.webp","width":253,"height":55,"caption":"Fenix Amortecedores"},"image":{"@id":"https:\/\/www.fenixamortecedores.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fenixamortecedores.com.br\/blog\/wp-json\/wp\/v2\/tags\/950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fenixamortecedores.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.fenixamortecedores.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.fenixamortecedores.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}